{"id":25,"count":3,"description":"Discover the ingredients, techniques, family memories, and regional traditions behind everyday Fujian food.","link":"https:\/\/eastorya.com\/ko\/category\/local-stories\/food-stories\/","name":"Food Stories","slug":"food-stories","taxonomy":"category","parent":16,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/eastorya.com\/ko\/wp-json\/wp\/v2\/categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eastorya.com\/ko\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/eastorya.com\/ko\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/eastorya.com\/ko\/wp-json\/wp\/v2\/categories\/16"}],"wp:post_type":[{"href":"https:\/\/eastorya.com\/ko\/wp-json\/wp\/v2\/posts?categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}